{"id":15343,"date":"2024-04-15T11:31:18","date_gmt":"2024-04-15T09:31:18","guid":{"rendered":"https:\/\/sct.webs.upv.es\/?p=15343"},"modified":"2024-04-15T11:35:05","modified_gmt":"2024-04-15T09:35:05","slug":"concurso-robotica-2024","status":"publish","type":"post","link":"https:\/\/sct.webs.upv.es\/ca\/concurso-robotica-2024\/","title":{"rendered":"Celebrado el XI Concurso de Rob\u00f3tica M\u00f3vil del Campus de Alcoy de la UPV"},"content":{"rendered":"<p>Han participado m\u00e1s de 500 estudiantes de 17 centros educativos de las provincias de Alicante y Valencia<\/p>\n<p>El XI Concurso de Rob\u00f3tica M\u00f3vil, organizado por GROMEP, el Grupo de Rob\u00f3tica y Mecatr\u00f3nica y el Campus de Alcoy de la UPV, ha convocado a 17 institutos de Banyeres, Alicante, Denia, Petrer, Algemes\u00ed, Oliva, Villena, Benig\u00e1nim, Sant Joan, Cocentaina, Val\u00e8ncia y La Pobla del Duc. El concurso ha estado dirigido a estudiantes pertenecientes a centros educativos de Educaci\u00f3n Secundaria, Bachillerato o Ciclos Formativos de Formaci\u00f3n Profesional, entidades educativas y cualquier aficionado a la rob\u00f3tica.<\/p>\n<p><iframe title=\"Reproductor de v\u00eddeo de YouTube\" src=\"https:\/\/www.youtube.com\/embed\/ZThVSR8WWKs?si=y4rrLWtCsjm0Os1e\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Han participado m\u00e1s de 500 estudiantes, distribuidos en 232 equipos. La mayor\u00eda de premios se los han llevado institutos de Villena, Oliva y la Pobla del Duc. El pabell\u00f3n de deportes del Edificio Georgina Blanes, dentro de la programaci\u00f3n anual de \u2018J\u00f3venes con Ciencia\u2019, ha acogido este concurso ya consolidado. Cuenta con la colaboraci\u00f3n de la Fundaci\u00f3n Espa\u00f1ola para la Ciencia y la Tecnolog\u00eda \u2013 Ministerio de Ciencia, Innovaci\u00f3n y Universidades. Adem\u00e1s, tambi\u00e9n colabora la C\u00e1tedra \u00abAlcoy Ciudad del Conocimiento\u00bb firmada con el Ayuntamiento de Alcoy, la Obra Social de Caixa Ontinyent, y con el respaldo de Multiscan Technologies.<\/p>\n<p>Este concurso ya consolidado tiene como objetivo fomentar la rob\u00f3tica estimulando el aprendizaje en contenidos cient\u00edficos tales como las matem\u00e1ticas, f\u00edsica, inform\u00e1tica y mec\u00e1nica. Ha contado con las modalidades Recogebot Lego, Recogebot Libre, Lucha Libre, Lucha LEGO, Laberinto, Siguelineas LEGO y Siguelineas LIBRE.<\/p>\n<p><a href=\"https:\/\/www.flickr.com\/photos\/152475265@N05\/albums\/72177720314844569\"><strong>Todas las fotos<\/strong><\/a><\/p>\n<p><strong>Entrega de premios<\/strong><\/p>\n<p>Organizadores y patrocinadores han acudido a este certamen, como es el caso del concejal de Educaci\u00f3n del Ayuntamiento de Alcoy, Alberto Belda, la diputada nacional, Patricia Blanquer, o el jefe de zona de L\u2019Alcoi\u00e0 de Caixa Ontinyent, Jos\u00e9 Rafael Revert.<\/p>\n<p>Por parte del Campus de Alcoy de la UPV, han entregado los premios el director del Campus de Alcoy, Pau Bernabeu, el responsable del \u00c1rea de Planificaci\u00f3n y Desarrollo del Campus, Jes\u00fas Segu\u00ed, y los profesores, Jaime Masi\u00e1 y Juan Ram\u00f3n Rufino.<\/p>\n<p><strong>Premios modalidad \u201cSiguelineas LEGO\u201d<\/strong>\u00a01er clasificado categor\u00eda RCX: Supra MK4 del IES Las Fuentes de Villena<\/p>\n<p><strong>Premios modalidad \u201cSiguelineas LEGO\u201d<\/strong>\u00a01er clasificado categor\u00eda EV3: Funrib de la Fundaci\u00f3n Ribera de Banyeres<\/p>\n<p><strong>Premios modalidad \u201cSiguelineas LEGO\u201d\u00a0<\/strong>1er clasificado categor\u00eda SPIKE: Velorapid del IES Gabriel Ciscar de Oliva<\/p>\n<p><strong>Premios modalidad \u201cSiguelineas Libre\u201d\u00a0<\/strong>(Peso Mosca)\u201d: 1er clasificado: Tonibot del IES Las Fuentes de Villena<\/p>\n<p><strong>Premios modalidad \u201cSiguelineas Libre (Peso Pluma)\u201d:<\/strong>\u00a01er clasificado: Broski del IES Las Fuentes de Villena<\/p>\n<p><strong>Premios modalidad \u201cSiguelineas Libre (Peso Pesado)\u201d:<\/strong>\u00a01er clasificado: Javi-Nogales del IES Las Fuentes de Villena<\/p>\n<p><strong>Premios modalidad \u201cLucha LEGO\u201c<\/strong><\/p>\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-layout-1 wp-block-group-is-layout-flex\">\n<p>1\u00ba clasificado: Titan Force del IES Las Fuentes de Villena<\/p>\n<p>2\u00ba clasificado: Chiquibai del IES Las Fuentes de Villena<\/p>\n<p>3\u00ba clasificado: Botellazo del IES Las Fuentes de Villena<\/p>\n<\/div>\n<p><strong>Premios modalidad \u201cLucha libre\u201c<\/strong><\/p>\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-layout-2 wp-block-group-is-layout-flex\">\n<p>1\u00ba clasificado: Brikybot del IES Pobla del DUC<\/p>\n<p>2\u00ba clasificado: Gusbot del IES Pobla del Duc<\/p>\n<p>3\u00ba clasificado: Granero del IES Las Fuentes de Villena<\/p>\n<\/div>\n<p><strong>Premios modalidad \u201cLaberinto\u201d<\/strong><\/p>\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-layout-3 wp-block-group-is-layout-flex\">\n<p>1\u00ba clasificado: Alphazeta del IES Las Fuentes de Villena<\/p>\n<p>2\u00ba clasificado: Banana Joe del IES Las Fuentes de Villena<\/p>\n<p>3\u00ba clasificado: Pesca El ruso del IES Las Fuentes de Villena<\/p>\n<\/div>\n<p><strong>Premios modalidad \u201cRecogebot Lego \/ Libre \u201d<\/strong><\/p>\n<div class=\"wp-block-group is-vertical is-layout-flex wp-container-core-group-layout-4 wp-block-group-is-layout-flex\">\n<p>1\u00ba clasificado: Conta-les1 del IES Gabriel Ciscar de Oliva<\/p>\n<p>2\u00ba clasificado: Tobias1 del IES Gabriel Ciscar de Oliva<\/p>\n<p>3\u00ba clasificado: Salsitxes1 del IES Gabriel Ciscar de Oliva<\/p>\n<\/div>\n<p><strong>Premios modalidad \u201cRecogebot Taller\u201d<\/strong><\/p>\n<p>1\u00ba clasificado: Arale del Col.legi Sant Roc Alcoi<\/p>","protected":false},"excerpt":{"rendered":"<p>Han participado m\u00e1s de 500 estudiantes de 17 centros educativos de las provincias de Alicante y Valencia El XI Concurso de Rob\u00f3tica M\u00f3vil, organizado por GROMEP, el Grupo de Rob\u00f3tica [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":15341,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[51],"tags":[],"class_list":["post-15343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jovenesconciencia"],"acf":[],"_links":{"self":[{"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/posts\/15343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/comments?post=15343"}],"version-history":[{"count":1,"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/posts\/15343\/revisions"}],"predecessor-version":[{"id":15344,"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/posts\/15343\/revisions\/15344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/media\/15341"}],"wp:attachment":[{"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/media?parent=15343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/categories?post=15343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sct.webs.upv.es\/ca\/wp-json\/wp\/v2\/tags?post=15343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}